{"id":487,"date":"2024-11-02T19:23:42","date_gmt":"2024-11-02T19:23:42","guid":{"rendered":"https:\/\/palazzocitterio.org\/collezione-online\/opere\/the-garden\/"},"modified":"2024-11-02T19:23:42","modified_gmt":"2024-11-02T19:23:42","slug":"the-garden","status":"publish","type":"opera","link":"https:\/\/palazzocitterio.org\/en\/collezioni\/collezione-on-line\/the-garden\/","title":{"rendered":"The Garden"},"featured_media":3077,"template":"","opere-autore":[579],"opere-genere":[43,26],"opere-periodo":[168],"opere-sala":[934],"opere-tecnica":[170],"class_list":["post-487","opera","type-opera","status-publish","has-post-thumbnail","hentry","opere-autore-massimo-campigli-max-ihlenfeldt","opere-genere-donazioni-acquisizioni-en","opere-genere-works-display","opere-periodo-xx-secolo-d-c-en","opere-sala-45-en","opere-tecnica-oil-on-canvas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>The Garden | Palazzo Citterio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/palazzocitterio.org\/collezioni\/collezione-on-line\/il-giardino\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Garden\" \/>\n<meta property=\"og:url\" content=\"https:\/\/palazzocitterio.org\/collezioni\/collezione-on-line\/il-giardino\/\" \/>\n<meta property=\"og:site_name\" content=\"Palazzo Citterio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61566829379672\" \/>\n<meta property=\"og:image\" content=\"https:\/\/palazzocitterio.org\/wp-content\/uploads\/2024\/11\/Campigli-Giardino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"779\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/palazzocitterio.org\\\/collezioni\\\/collezione-on-line\\\/il-giardino\\\/\",\"url\":\"https:\\\/\\\/palazzocitterio.org\\\/collezioni\\\/collezione-on-line\\\/il-giardino\\\/\",\"name\":\"The Garden | Palazzo Citterio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/palazzocitterio.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/palazzocitterio.org\\\/collezioni\\\/collezione-on-line\\\/il-giardino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/palazzocitterio.org\\\/collezioni\\\/collezione-on-line\\\/il-giardino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/palazzocitterio.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Campigli-Giardino.jpg\",\"datePublished\":\"2024-11-02T19:23:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/palazzocitterio.org\\\/collezioni\\\/collezione-on-line\\\/il-giardino\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/palazzocitterio.org\\\/collezioni\\\/collezione-on-line\\\/il-giardino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/palazzocitterio.org\\\/collezioni\\\/collezione-on-line\\\/il-giardino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/palazzocitterio.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Campigli-Giardino.jpg\",\"contentUrl\":\"https:\\\/\\\/palazzocitterio.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Campigli-Giardino.jpg\",\"width\":1024,\"height\":779},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/palazzocitterio.org\\\/collezioni\\\/collezione-on-line\\\/il-giardino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/palazzocitterio.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Garden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/palazzocitterio.org\\\/#website\",\"url\":\"https:\\\/\\\/palazzocitterio.org\\\/\",\"name\":\"Palazzo Citterio\",\"description\":\"Grande Brera\",\"publisher\":{\"@id\":\"https:\\\/\\\/palazzocitterio.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/palazzocitterio.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/palazzocitterio.org\\\/#organization\",\"name\":\"Palazzo Citterio\",\"url\":\"https:\\\/\\\/palazzocitterio.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/palazzocitterio.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/palazzocitterio.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Palazzo_Citterio-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/palazzocitterio.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Palazzo_Citterio-logo.jpg\",\"width\":600,\"height\":600,\"caption\":\"Palazzo Citterio\"},\"image\":{\"@id\":\"https:\\\/\\\/palazzocitterio.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61566829379672\",\"https:\\\/\\\/www.instagram.com\\\/palazzocitterio.brera\\\/\"],\"description\":\"Palazzo Citterio, nel cuore della Grande Brera, ospita capolavori del Novecento, tra cui Boccioni e Picasso, e mostre di arte contemporanea.\",\"legalName\":\"Palazzo Citterio\",\"foundingDate\":\"2024-12-07\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"The Garden | Palazzo Citterio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/palazzocitterio.org\/collezioni\/collezione-on-line\/il-giardino\/","og_locale":"en_US","og_type":"article","og_title":"The Garden","og_url":"https:\/\/palazzocitterio.org\/collezioni\/collezione-on-line\/il-giardino\/","og_site_name":"Palazzo Citterio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61566829379672","og_image":[{"width":1024,"height":779,"url":"https:\/\/palazzocitterio.org\/wp-content\/uploads\/2024\/11\/Campigli-Giardino.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/palazzocitterio.org\/collezioni\/collezione-on-line\/il-giardino\/","url":"https:\/\/palazzocitterio.org\/collezioni\/collezione-on-line\/il-giardino\/","name":"The Garden | Palazzo Citterio","isPartOf":{"@id":"https:\/\/palazzocitterio.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/palazzocitterio.org\/collezioni\/collezione-on-line\/il-giardino\/#primaryimage"},"image":{"@id":"https:\/\/palazzocitterio.org\/collezioni\/collezione-on-line\/il-giardino\/#primaryimage"},"thumbnailUrl":"https:\/\/palazzocitterio.org\/wp-content\/uploads\/2024\/11\/Campigli-Giardino.jpg","datePublished":"2024-11-02T19:23:42+00:00","breadcrumb":{"@id":"https:\/\/palazzocitterio.org\/collezioni\/collezione-on-line\/il-giardino\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/palazzocitterio.org\/collezioni\/collezione-on-line\/il-giardino\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/palazzocitterio.org\/collezioni\/collezione-on-line\/il-giardino\/#primaryimage","url":"https:\/\/palazzocitterio.org\/wp-content\/uploads\/2024\/11\/Campigli-Giardino.jpg","contentUrl":"https:\/\/palazzocitterio.org\/wp-content\/uploads\/2024\/11\/Campigli-Giardino.jpg","width":1024,"height":779},{"@type":"BreadcrumbList","@id":"https:\/\/palazzocitterio.org\/collezioni\/collezione-on-line\/il-giardino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/palazzocitterio.org\/en\/"},{"@type":"ListItem","position":2,"name":"The Garden"}]},{"@type":"WebSite","@id":"https:\/\/palazzocitterio.org\/#website","url":"https:\/\/palazzocitterio.org\/","name":"Palazzo Citterio","description":"Grande Brera","publisher":{"@id":"https:\/\/palazzocitterio.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/palazzocitterio.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/palazzocitterio.org\/#organization","name":"Palazzo Citterio","url":"https:\/\/palazzocitterio.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/palazzocitterio.org\/#\/schema\/logo\/image\/","url":"https:\/\/palazzocitterio.org\/wp-content\/uploads\/2024\/12\/Palazzo_Citterio-logo.jpg","contentUrl":"https:\/\/palazzocitterio.org\/wp-content\/uploads\/2024\/12\/Palazzo_Citterio-logo.jpg","width":600,"height":600,"caption":"Palazzo Citterio"},"image":{"@id":"https:\/\/palazzocitterio.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61566829379672","https:\/\/www.instagram.com\/palazzocitterio.brera\/"],"description":"Palazzo Citterio, nel cuore della Grande Brera, ospita capolavori del Novecento, tra cui Boccioni e Picasso, e mostre di arte contemporanea.","legalName":"Palazzo Citterio","foundingDate":"2024-12-07"}]}},"_links":{"self":[{"href":"https:\/\/palazzocitterio.org\/en\/wp-json\/wp\/v2\/opera\/487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palazzocitterio.org\/en\/wp-json\/wp\/v2\/opera"}],"about":[{"href":"https:\/\/palazzocitterio.org\/en\/wp-json\/wp\/v2\/types\/opera"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/palazzocitterio.org\/en\/wp-json\/wp\/v2\/media\/3077"}],"wp:attachment":[{"href":"https:\/\/palazzocitterio.org\/en\/wp-json\/wp\/v2\/media?parent=487"}],"wp:term":[{"taxonomy":"opere-autore","embeddable":true,"href":"https:\/\/palazzocitterio.org\/en\/wp-json\/wp\/v2\/opere-autore?post=487"},{"taxonomy":"opere-genere","embeddable":true,"href":"https:\/\/palazzocitterio.org\/en\/wp-json\/wp\/v2\/opere-genere?post=487"},{"taxonomy":"opere-periodo","embeddable":true,"href":"https:\/\/palazzocitterio.org\/en\/wp-json\/wp\/v2\/opere-periodo?post=487"},{"taxonomy":"opere-sala","embeddable":true,"href":"https:\/\/palazzocitterio.org\/en\/wp-json\/wp\/v2\/opere-sala?post=487"},{"taxonomy":"opere-tecnica","embeddable":true,"href":"https:\/\/palazzocitterio.org\/en\/wp-json\/wp\/v2\/opere-tecnica?post=487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}